{"id":469,"date":"2026-06-09T09:29:59","date_gmt":"2026-06-09T09:29:59","guid":{"rendered":"https:\/\/verdeleria.com\/communication\/"},"modified":"2026-06-16T10:28:10","modified_gmt":"2026-06-16T10:28:10","slug":"communication","status":"publish","type":"page","link":"https:\/\/verdeleria.com\/en\/communication\/","title":{"rendered":"Communication"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; full_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;17%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;17%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Presentation for the Cosentino Group, at its headquarters in O Porri\u00f1o, titled \u201cBorrowed Landscapes: Allies with Nature and the Place\u201d<\/strong><br \/>\n<span style=\"font-weight: 400;\">November 2024<\/span><\/p>\n<p><strong>Publication of the Vidalverde house and mention in the professionals section of the digital magazine Ex\u00e1gono<\/strong><br \/>\n<span style=\"font-weight: 400;\">March 2025. <a class=\"nectar-button n-sc-button medium see-through-2\" target=\"_blank\" href=\"https:\/\/exagono.es\/profesionales\/maria-hernandez-lopez-verde-leria\/\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>View news<\/span><\/a><\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; full_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":468,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-469","page","type-page","status-publish","has-post-thumbnail"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Presentation for the Cosentino Group, at its headquarters in O Porri\u00f1o, titled \u201cBorrowed Landscapes: Allies with Nature and the Place\u201d November 2024 Publication of the Vidalverde house and mention in the professionals section of the digital magazine Ex\u00e1gono March 2025. View news\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/verdeleria.com\/en\/communication\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Estudio de paisajismo y arquitectura de exteriores. - Estudio de dise\u00f1o paisaj\u00edstico y de jardines en Galicia\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Communication - Estudio de paisajismo y arquitectura de exteriores.\" \/>\n\t\t<meta property=\"og:description\" content=\"Presentation for the Cosentino Group, at its headquarters in O Porri\u00f1o, titled \u201cBorrowed Landscapes: Allies with Nature and the Place\u201d November 2024 Publication of the Vidalverde house and mention in the professionals section of the digital magazine Ex\u00e1gono March 2025. View news\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/verdeleria.com\/en\/communication\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-06-09T09:29:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-16T10:28:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Communication - Estudio de paisajismo y arquitectura de exteriores.\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Presentation for the Cosentino Group, at its headquarters in O Porri\u00f1o, titled \u201cBorrowed Landscapes: Allies with Nature and the Place\u201d November 2024 Publication of the Vidalverde house and mention in the professionals section of the digital magazine Ex\u00e1gono March 2025. View news\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/communication\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/communication\\\/#listItem\",\"name\":\"Communication\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/communication\\\/#listItem\",\"position\":2,\"name\":\"Communication\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/#organization\",\"name\":\"Estudio de paisajismo y arquitectura de exteriores.\",\"description\":\"Estudio de dise\\u00f1o paisaj\\u00edstico y de jardines en Galicia\",\"url\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/communication\\\/#webpage\",\"url\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/communication\\\/\",\"name\":\"Communication - Estudio de paisajismo y arquitectura de exteriores.\",\"description\":\"Presentation for the Cosentino Group, at its headquarters in O Porri\\u00f1o, titled \\u201cBorrowed Landscapes: Allies with Nature and the Place\\u201d November 2024 Publication of the Vidalverde house and mention in the professionals section of the digital magazine Ex\\u00e1gono March 2025. View news\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/communication\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/verdeleria.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Portada_Comunicacion_Verde-Leria.webp\",\"@id\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/communication\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/communication\\\/#mainImage\"},\"datePublished\":\"2026-06-09T09:29:59+00:00\",\"dateModified\":\"2026-06-16T10:28:10+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/\",\"name\":\"Estudio de paisajismo y arquitectura de exteriores.\",\"description\":\"Estudio de dise\\u00f1o paisaj\\u00edstico y de jardines en Galicia\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/verdeleria.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Communication - Estudio de paisajismo y arquitectura de exteriores.","description":"Presentation for the Cosentino Group, at its headquarters in O Porri\u00f1o, titled \u201cBorrowed Landscapes: Allies with Nature and the Place\u201d November 2024 Publication of the Vidalverde house and mention in the professionals section of the digital magazine Ex\u00e1gono March 2025. View news","canonical_url":"https:\/\/verdeleria.com\/en\/communication\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/verdeleria.com\/en\/communication\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/verdeleria.com\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/verdeleria.com\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/verdeleria.com\/en\/communication\/#listItem","name":"Communication"}},{"@type":"ListItem","@id":"https:\/\/verdeleria.com\/en\/communication\/#listItem","position":2,"name":"Communication","previousItem":{"@type":"ListItem","@id":"https:\/\/verdeleria.com\/en\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/verdeleria.com\/en\/#organization","name":"Estudio de paisajismo y arquitectura de exteriores.","description":"Estudio de dise\u00f1o paisaj\u00edstico y de jardines en Galicia","url":"https:\/\/verdeleria.com\/en\/"},{"@type":"WebPage","@id":"https:\/\/verdeleria.com\/en\/communication\/#webpage","url":"https:\/\/verdeleria.com\/en\/communication\/","name":"Communication - Estudio de paisajismo y arquitectura de exteriores.","description":"Presentation for the Cosentino Group, at its headquarters in O Porri\u00f1o, titled \u201cBorrowed Landscapes: Allies with Nature and the Place\u201d November 2024 Publication of the Vidalverde house and mention in the professionals section of the digital magazine Ex\u00e1gono March 2025. View news","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/verdeleria.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/verdeleria.com\/en\/communication\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/verdeleria.com\/wp-content\/uploads\/2026\/06\/Portada_Comunicacion_Verde-Leria.webp","@id":"https:\/\/verdeleria.com\/en\/communication\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/verdeleria.com\/en\/communication\/#mainImage"},"datePublished":"2026-06-09T09:29:59+00:00","dateModified":"2026-06-16T10:28:10+00:00"},{"@type":"WebSite","@id":"https:\/\/verdeleria.com\/en\/#website","url":"https:\/\/verdeleria.com\/en\/","name":"Estudio de paisajismo y arquitectura de exteriores.","description":"Estudio de dise\u00f1o paisaj\u00edstico y de jardines en Galicia","inLanguage":"en-US","publisher":{"@id":"https:\/\/verdeleria.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Estudio de paisajismo y arquitectura de exteriores. - Estudio de dise\u00f1o paisaj\u00edstico y de jardines en Galicia","og:type":"article","og:title":"Communication - Estudio de paisajismo y arquitectura de exteriores.","og:description":"Presentation for the Cosentino Group, at its headquarters in O Porri\u00f1o, titled \u201cBorrowed Landscapes: Allies with Nature and the Place\u201d November 2024 Publication of the Vidalverde house and mention in the professionals section of the digital magazine Ex\u00e1gono March 2025. View news","og:url":"https:\/\/verdeleria.com\/en\/communication\/","article:published_time":"2026-06-09T09:29:59+00:00","article:modified_time":"2026-06-16T10:28:10+00:00","twitter:card":"summary_large_image","twitter:title":"Communication - Estudio de paisajismo y arquitectura de exteriores.","twitter:description":"Presentation for the Cosentino Group, at its headquarters in O Porri\u00f1o, titled \u201cBorrowed Landscapes: Allies with Nature and the Place\u201d November 2024 Publication of the Vidalverde house and mention in the professionals section of the digital magazine Ex\u00e1gono March 2025. View news"},"aioseo_meta_data":{"post_id":"469","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-06-16 10:28:10","updated":"2026-06-16 10:31:16","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/verdeleria.com\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCommunication\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/verdeleria.com\/en\/"},{"label":"Communication","link":"https:\/\/verdeleria.com\/en\/communication\/"}],"_links":{"self":[{"href":"https:\/\/verdeleria.com\/en\/wp-json\/wp\/v2\/pages\/469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verdeleria.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/verdeleria.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/verdeleria.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/verdeleria.com\/en\/wp-json\/wp\/v2\/comments?post=469"}],"version-history":[{"count":2,"href":"https:\/\/verdeleria.com\/en\/wp-json\/wp\/v2\/pages\/469\/revisions"}],"predecessor-version":[{"id":471,"href":"https:\/\/verdeleria.com\/en\/wp-json\/wp\/v2\/pages\/469\/revisions\/471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/verdeleria.com\/en\/wp-json\/wp\/v2\/media\/468"}],"wp:attachment":[{"href":"https:\/\/verdeleria.com\/en\/wp-json\/wp\/v2\/media?parent=469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}